{"id":2219,"count":1,"description":"","link":"https:\/\/latribune.lazardfreresgestion.fr\/en\/tag\/long-term-rates\/","name":"long-term rates","slug":"long-term-rates","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion<\/title>\n<meta name=\"description\" content=\"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion\" \/>\n<meta property=\"og:description\" content=\"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latribune.lazardfreresgestion.fr\/en\/tag\/long-term-rates\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribune Lazard Fr\u00e8res Gestion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LazardGestion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/tag\\\/long-term-rates\\\/\",\"url\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/tag\\\/long-term-rates\\\/\",\"name\":\"long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#website\"},\"description\":\"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/\",\"name\":\"Tribune Lazard Fr\u00e8res Gestion\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#organization\",\"name\":\"Lazard Fr\u00e8res Gestion\",\"url\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGOLINKEDINVF-2.png\",\"contentUrl\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGOLINKEDINVF-2.png\",\"width\":5000,\"height\":5000,\"caption\":\"Lazard Fr\u00e8res Gestion\"},\"image\":{\"@id\":\"https:\\\/\\\/latribune.lazardfreresgestion.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/LazardGestion\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lazard-freres-gestion\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCI1a03ScxMW6clPl82UO_tQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion","description":"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion","og_description":"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion","og_url":"https:\/\/latribune.lazardfreresgestion.fr\/en\/tag\/long-term-rates\/","og_site_name":"Tribune Lazard Fr\u00e8res Gestion","twitter_card":"summary_large_image","twitter_site":"@LazardGestion","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/tag\/long-term-rates\/","url":"https:\/\/latribune.lazardfreresgestion.fr\/en\/tag\/long-term-rates\/","name":"long-term rates Archives &#8211; Tribune Lazard Fr\u00e8res Gestion","isPartOf":{"@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#website"},"description":"long-term rates &#8211; Tribune Lazard Fr\u00e8res Gestion","inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#website","url":"https:\/\/latribune.lazardfreresgestion.fr\/en\/","name":"Tribune Lazard Fr\u00e8res Gestion","description":"Blog","publisher":{"@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latribune.lazardfreresgestion.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#organization","name":"Lazard Fr\u00e8res Gestion","url":"https:\/\/latribune.lazardfreresgestion.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/latribune.lazardfreresgestion.fr\/wp-content\/uploads\/2019\/03\/LOGOLINKEDINVF-2.png","contentUrl":"https:\/\/latribune.lazardfreresgestion.fr\/wp-content\/uploads\/2019\/03\/LOGOLINKEDINVF-2.png","width":5000,"height":5000,"caption":"Lazard Fr\u00e8res Gestion"},"image":{"@id":"https:\/\/latribune.lazardfreresgestion.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/LazardGestion","https:\/\/www.linkedin.com\/company\/lazard-freres-gestion\/","https:\/\/www.youtube.com\/channel\/UCI1a03ScxMW6clPl82UO_tQ"]}]}},"_links":{"self":[{"href":"https:\/\/latribune.lazardfreresgestion.fr\/en\/wp-json\/wp\/v2\/tags\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latribune.lazardfreresgestion.fr\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/latribune.lazardfreresgestion.fr\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/latribune.lazardfreresgestion.fr\/en\/wp-json\/wp\/v2\/posts?tags=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}